{"id":354,"date":"2019-01-11T11:15:12","date_gmt":"2019-01-11T11:15:12","guid":{"rendered":"https:\/\/aquilasrl.net\/?page_id=354"},"modified":"2019-01-15T11:32:25","modified_gmt":"2019-01-15T11:32:25","slug":"catalogue","status":"publish","type":"page","link":"https:\/\/aquilasrl.net\/en\/catalogue\/","title":{"rendered":"Catalogue"},"content":{"rendered":"<p><hr class=\"no_line\" style=\"margin: 0 auto 10px auto\"\/>\n<br \/>\n<center><\/p>\n<div style=\"width: 150px; height: 3px; background: #dddddd;\"><\/div>\n<hr class=\"no_line\" style=\"margin: 0 auto 30px auto\"\/>\n\n<h2>Aquila SRL<br \/><span class=\"themecolor\">catalogue<\/span><\/h2>\n<p><\/center><br \/>\n<hr class=\"no_line\" style=\"margin: 0 auto 10px auto\"\/>\n<br \/>\n<!-- ipages begin -->\n<div class=\"ipgs-flipbook ipgs-1\" data-json-src=\"https:\/\/aquilasrl.net\/en\/wp-json\/ipages\/v1\/item\/1\" data-item-id=\"1\" style=\"display:none;\">\n<\/div>\n<!-- ipages end -->\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquila SRLcatalogue<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-354","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catalogue - Aquila Srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquilasrl.net\/catalogo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalogue - Aquila Srl\" \/>\n<meta property=\"og:description\" content=\"Aquila SRLcatalogue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquilasrl.net\/catalogo\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquila Srl\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-15T11:32:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquilasrl.net\\\/catalogo\\\/\",\"url\":\"https:\\\/\\\/aquilasrl.net\\\/catalogo\\\/\",\"name\":\"Catalogue - Aquila Srl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquilasrl.net\\\/#website\"},\"datePublished\":\"2019-01-11T11:15:12+00:00\",\"dateModified\":\"2019-01-15T11:32:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquilasrl.net\\\/catalogo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquilasrl.net\\\/catalogo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquilasrl.net\\\/catalogo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquilasrl.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquilasrl.net\\\/#website\",\"url\":\"https:\\\/\\\/aquilasrl.net\\\/\",\"name\":\"Aquila Srl\",\"description\":\"Aquila\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquilasrl.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalogue - Aquila Srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquilasrl.net\/catalogo\/","og_locale":"en_US","og_type":"article","og_title":"Catalogue - Aquila Srl","og_description":"Aquila SRLcatalogue","og_url":"https:\/\/aquilasrl.net\/catalogo\/","og_site_name":"Aquila Srl","article_modified_time":"2019-01-15T11:32:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquilasrl.net\/catalogo\/","url":"https:\/\/aquilasrl.net\/catalogo\/","name":"Catalogue - Aquila Srl","isPartOf":{"@id":"https:\/\/aquilasrl.net\/#website"},"datePublished":"2019-01-11T11:15:12+00:00","dateModified":"2019-01-15T11:32:25+00:00","breadcrumb":{"@id":"https:\/\/aquilasrl.net\/catalogo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquilasrl.net\/catalogo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aquilasrl.net\/catalogo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquilasrl.net\/"},{"@type":"ListItem","position":2,"name":"Catalogue"}]},{"@type":"WebSite","@id":"https:\/\/aquilasrl.net\/#website","url":"https:\/\/aquilasrl.net\/","name":"Aquila Srl","description":"Aquila","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquilasrl.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/pages\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":2,"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/pages\/354\/revisions"}],"predecessor-version":[{"id":364,"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/pages\/354\/revisions\/364"}],"wp:attachment":[{"href":"https:\/\/aquilasrl.net\/en\/wp-json\/wp\/v2\/media?parent=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}